{"id":926,"date":"2023-02-05T21:00:49","date_gmt":"2023-02-05T21:00:49","guid":{"rendered":"https:\/\/oracionhuerto.es\/?p=926"},"modified":"2023-02-05T21:00:51","modified_gmt":"2023-02-05T21:00:51","slug":"bendicion-y-celebracion-de-santa-agueda","status":"publish","type":"post","link":"https:\/\/oracionhuerto.com.es\/index.php\/2023\/02\/05\/bendicion-y-celebracion-de-santa-agueda\/","title":{"rendered":"Bendici\u00f3n y celebraci\u00f3n de Santa \u00c1gueda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hoy, 5 de febrero, ha sido la <a href=\"https:\/\/www.parroquiadelportillo.es\/single-post\/santa-%C3%A1gueda-cuidar-la-vida-erradicar-la-violencia\" data-type=\"URL\" data-id=\"https:\/\/www.parroquiadelportillo.es\/single-post\/santa-%C3%A1gueda-cuidar-la-vida-erradicar-la-violencia\" target=\"_blank\" rel=\"noreferrer noopener\">Fiesta y Celebraci\u00f3n de Santa \u00c1gueda<\/a>, m\u00e1rtir del siglo III. Considerada protectora de las mujeres, debido al <a rel=\"noreferrer noopener\" href=\"https:\/\/www.elespanol.com\/mujer\/mujeres-historia\/santa-agueda-dia-mujer-martir-cortaron-pecho\/646935410_0.html#:~:text=Debido%20al%20martirio%20que%20sufri%C3%B3,la%20patrona%20de%20las%20enfermeras.\" data-type=\"URL\" data-id=\"https:\/\/www.elespanol.com\/mujer\/mujeres-historia\/santa-agueda-dia-mujer-martir-cortaron-pecho\/646935410_0.html#:~:text=Debido%20al%20martirio%20que%20sufri%C3%B3,la%20patrona%20de%20las%20enfermeras.\" target=\"_blank\">martirio que sufri\u00f3<\/a>, sus reliquias (sus pechos cortados en dicho martirio), descansan en la iglesia de Nuestra Se\u00f1ora del Portillo de Zaragoza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un d\u00eda en el que sus reliquias se exponen para su veneraci\u00f3n, generando una gran afluencia. Por ello desde nuestra Cofrad\u00eda nos hemos dedicado estos meses a realizar trabajos de limpieza y conservaci\u00f3n de la talla de la Santa, as\u00ed como del altar donde est\u00e1 alojada. El d\u00eda 3 de febrero, una vez finalizados dichos trabajos, asistimos a la Bendici\u00f3n por nuestro Se\u00f1or P\u00e1rroco D. Jes\u00fas Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, al d\u00eda siguiente, v\u00edspera de Santa \u00c1gueda, Se celebr\u00f3 un encuentro-oraci\u00f3n organizado por nuestra Cofrad\u00eda, junto con la Parroquia y la Junta Coordinadora de Cofrad\u00edas, por el mismo motivo, siendo invitadas todas nuestras hermanas cofrades, y diversas autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ambos actos os dejamos varias fotograf\u00edas. Adem\u00e1s tambi\u00e9n os facilitamos el enlace a la noticia de <a rel=\"noreferrer noopener\" href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/2023\/02\/05\/miles-de-zaragozanos-celebran-santa-agueda-como-simbolo-de-la-igualdad-1629171.html\" data-type=\"URL\" data-id=\"https:\/\/www.heraldo.es\/noticias\/aragon\/2023\/02\/05\/miles-de-zaragozanos-celebran-santa-agueda-como-simbolo-de-la-igualdad-1629171.html\" target=\"_blank\">Heraldo de Arag\u00f3n en referencia a la Fiesta y ambos actos<\/a>, y a sus <a rel=\"noreferrer noopener\" href=\"https:\/\/www.heraldo.es\/multimedia\/imagenes\/aragon\/zaragoza\/celebracion-del-dia-de-santa-agueda-en-zaragoza\/27\/\" target=\"_blank\">im\u00e1genes<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las siguientes fotograf\u00edas son gentileza de Antonio Alejaldre, estrecho colaborador de nuestra Cofrad\u00eda, e Isabel Hernando, muy implicada en la Parroquia, siendo la encargada de su p\u00e1gina web. Para verlas en tama\u00f1o grande, pod\u00e9is hacer clic en cada una de ellas<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/DSC_8903-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"930\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/DSC_8903-1024x683.jpg\" alt=\"\" class=\"wp-image-930\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8903-1024x683.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8903-300x200.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8903-768x512.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8903-1536x1024.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8903-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/DSC_8910-scaled.jpg\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"929\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/DSC_8910-683x1024.jpg\" alt=\"\" class=\"wp-image-929\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8910-683x1024.jpg 683w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8910-200x300.jpg 200w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8910-768x1152.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8910-1024x1536.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8910-1365x2048.jpg 1365w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8910-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/DSC_8917-scaled.jpg\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"928\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/DSC_8917-683x1024.jpg\" alt=\"\" class=\"wp-image-928\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8917-683x1024.jpg 683w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8917-200x300.jpg 200w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8917-768x1152.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8917-1024x1536.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8917-1365x2048.jpg 1365w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/DSC_8917-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_190209-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"933\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_190209-1024x768.jpg\" alt=\"\" class=\"wp-image-933\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190209-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190209-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190209-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190209-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190209-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_190216-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"938\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_190216-1024x768.jpg\" alt=\"\" class=\"wp-image-938\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190216-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190216-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190216-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190216-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_190216-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_203051-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"931\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_203051-1024x768.jpg\" alt=\"\" class=\"wp-image-931\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203051-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203051-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203051-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203051-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203051-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_203925-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"935\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_203925-768x1024.jpg\" alt=\"\" class=\"wp-image-935\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203925-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203925-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203925-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203925-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203925-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_204236-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"932\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_204236-1024x768.jpg\" alt=\"\" class=\"wp-image-932\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204236-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204236-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204236-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204236-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204236-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_204521-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"936\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_204521-1024x768.jpg\" alt=\"\" class=\"wp-image-936\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204521-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204521-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204521-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204521-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_204521-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_205039-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"934\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_205039-1024x768.jpg\" alt=\"\" class=\"wp-image-934\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205039-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205039-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205039-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205039-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205039-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_205120-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"939\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_205120-1024x768.jpg\" alt=\"\" class=\"wp-image-939\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205120-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205120-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205120-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205120-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_205120-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201638-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"941\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201638-768x1024.jpg\" alt=\"\" class=\"wp-image-941\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201638-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201638-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201638-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201638-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201638-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201907-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"944\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201907-1024x768.jpg\" alt=\"\" class=\"wp-image-944\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201907-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201907-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201907-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201907-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201907-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_202247-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"945\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_202247-1024x768.jpg\" alt=\"\" class=\"wp-image-945\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202247-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202247-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202247-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202247-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202247-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_202503-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"946\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_202503-768x1024.jpg\" alt=\"\" class=\"wp-image-946\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202503-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202503-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202503-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202503-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_202503-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_203456-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"948\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_203456-768x1024.jpg\" alt=\"\" class=\"wp-image-948\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203456-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203456-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203456-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203456-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203456-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_203211-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"947\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_203211-768x1024.jpg\" alt=\"\" class=\"wp-image-947\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203211-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203211-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203211-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203211-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_203211-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201806-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"943\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201806-1024x768.jpg\" alt=\"\" class=\"wp-image-943\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201806-1024x768.jpg 1024w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201806-300x225.jpg 300w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201806-768x576.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201806-1536x1152.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201806-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201729-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"942\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230203_201729-768x1024.jpg\" alt=\"\" class=\"wp-image-942\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201729-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201729-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201729-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201729-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230203_201729-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_203301-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"937\" src=\"https:\/\/oracionhuerto.es\/wp-content\/uploads\/2023\/02\/20230204_203301-768x1024.jpg\" alt=\"\" class=\"wp-image-937\" srcset=\"https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203301-768x1024.jpg 768w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203301-225x300.jpg 225w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203301-1152x1536.jpg 1152w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203301-1536x2048.jpg 1536w, https:\/\/oracionhuerto.com.es\/wp-content\/uploads\/2023\/02\/20230204_203301-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, 5 de febrero, ha sido la Fiesta y Celebraci\u00f3n de Santa \u00c1gueda, m\u00e1rtir del siglo III. Considerada protectora de las mujeres, debido al martirio que sufri\u00f3, sus reliquias (sus pechos cortados en dicho martirio), descansan en la iglesia de Nuestra Se\u00f1ora del Portillo de Zaragoza. Es un d\u00eda en el que sus reliquias se &#8230; <a title=\"Bendici\u00f3n y celebraci\u00f3n de Santa \u00c1gueda\" class=\"read-more\" href=\"https:\/\/oracionhuerto.com.es\/index.php\/2023\/02\/05\/bendicion-y-celebracion-de-santa-agueda\/\" aria-label=\"Leer m\u00e1s sobre Bendici\u00f3n y celebraci\u00f3n de Santa \u00c1gueda\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"Restauraci\u00f3n, Bendici\u00f3n y Celebraci\u00f3n de Santa Agueda en Ntra. Sra del Portillo, en las que varios de nuestros hermanos han colaborado activamente.  @ssantazaragoza @heraldoes","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[10,8,9,7],"class_list":["post-926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parroquia","tag-cofradia","tag-parroquia","tag-restauracion","tag-santa-agueda"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/posts\/926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/comments?post=926"}],"version-history":[{"count":3,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/posts\/926\/revisions"}],"predecessor-version":[{"id":949,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/posts\/926\/revisions\/949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/media\/932"}],"wp:attachment":[{"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/media?parent=926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/categories?post=926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oracionhuerto.com.es\/index.php\/wp-json\/wp\/v2\/tags?post=926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}